{"id":61,"date":"2024-04-02T11:09:22","date_gmt":"2024-04-02T11:09:22","guid":{"rendered":"https:\/\/wpthemes.themehunk.com\/bigstore-multivendor\/?post_type=product&#038;p=61"},"modified":"2024-04-02T11:09:38","modified_gmt":"2024-04-02T11:09:38","slug":"bag-6","status":"publish","type":"product","link":"https:\/\/wpthemes.themehunk.com\/bigstore-multivendor\/product\/bag-6\/","title":{"rendered":"Bag 6"},"content":{"rendered":"<p>At vero eos et accusamus et iusto odio dignissimos ducimus qui blanditiis praesentium voluptatum deleniti atque corrupti quos dolores et quas molestias excepturi sint occaecati cupiditate non provident, similique sunt in culpa qui officia deserunt mollitia animi, id est laborum et dolorum fuga. Et harum quidem rerum facilis est et expedita distinctio. Nam libero tempore, cum soluta nobis est eligendi optio cumque nihil impedit quo minus id quod maxime placeat facere possimus, omnis voluptas assumenda est, omnis dolor repellendus. Temporibus autem quibusdam et aut officiis debitis aut rerum necessitatibus saepe eveniet ut et voluptates repudiandae sint et molestiae non recusandae. Itaque earum rerum hic tenetur a sapiente delectus, ut aut reiciendis voluptatibus maiores alias consequatur aut perferendis doloribus asperiores repellat.&#8221;<\/p>\n<p>&#8220;At vero eos et accusamus et iusto odio dignissimos ducimus qui blanditiis praesentium voluptatum deleniti atque corrupti quos dolores et quas molestias excepturi sint occaecati cupiditate non provident, similique sunt in culpa qui officia deserunt mollitia animi, id est laborum et dolorum fuga. Et harum quidem rerum facilis est et expedita distinctio. Nam libero tempore,<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;At vero eos et accusamus et iusto odio dignissimos ducimus qui blanditiis praesentium voluptatum deleniti atque corrupti quos dolores et quas molestias excepturi sint occaecati cupiditate non provident, similique sunt in culpa qui officia deserunt mollitia animi, id est laborum et dolorum fuga. Et harum quidem rerum facilis est et expedita distinctio. Nam libero tempore,<\/p>\n","protected":false},"featured_media":74,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[48],"product_tag":[],"class_list":{"0":"post-61","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-shoulder-bags","7":"thunk-woo-product-list","8":"opn-qv-enable","9":"big-store-woo-hover-","10":"open-single-product-tab-horizontal","11":"open-shadow-","12":"open-shadow-hover-","14":"first","15":"instock","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/wpthemes.themehunk.com\/bigstore-multivendor\/wp-json\/wp\/v2\/product\/61","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wpthemes.themehunk.com\/bigstore-multivendor\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/wpthemes.themehunk.com\/bigstore-multivendor\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/wpthemes.themehunk.com\/bigstore-multivendor\/wp-json\/wp\/v2\/comments?post=61"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wpthemes.themehunk.com\/bigstore-multivendor\/wp-json\/wp\/v2\/media\/74"}],"wp:attachment":[{"href":"https:\/\/wpthemes.themehunk.com\/bigstore-multivendor\/wp-json\/wp\/v2\/media?parent=61"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/wpthemes.themehunk.com\/bigstore-multivendor\/wp-json\/wp\/v2\/product_brand?post=61"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/wpthemes.themehunk.com\/bigstore-multivendor\/wp-json\/wp\/v2\/product_cat?post=61"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/wpthemes.themehunk.com\/bigstore-multivendor\/wp-json\/wp\/v2\/product_tag?post=61"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}