{"id":248,"date":"2020-08-20T11:03:00","date_gmt":"2020-08-20T11:03:00","guid":{"rendered":"https:\/\/wpthemes.themehunk.com\/pet-world\/?post_type=product&#038;p=248"},"modified":"2020-08-20T11:03:14","modified_gmt":"2020-08-20T11:03:14","slug":"1","status":"publish","type":"product","link":"https:\/\/wpthemes.themehunk.com\/pet-world\/product\/1\/","title":{"rendered":"Pet Collars 1"},"content":{"rendered":"<p>Integer feugiat eget quam non egestas. Fusce ullamcorper dapibus eleifend. Nullam ornare pulvinar lacinia. Nunc tempus facilisis ullamcorper. Nam sit amet suscipit risus, ut ultricies felis. Vivamus a finibus nisi. Sed quam sem, accumsan eget tristique sit amet, suscipit sit amet augue. Duis dolor dui, sagittis at faucibus ac, varius et sapienInteger feugiat eget quam non egestas. Fusce ullamcorper dapibus eleifend. Nullam ornare pulvinar lacinia. Nunc tempus facilisis ullamcorper. Nam sit amet suscipit risus, ut ultricies felis. Vivamus a finibus nisi. Sed quam sem, accumsan eget tristique sit amet, suscipit sit amet augue. Duis dolor dui, sagittis at faucibus ac, varius et sapien<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Integer feugiat eget quam non egestas. Fusce ullamcorper dapibus eleifend. Nullam ornare pulvinar lacinia. Nunc tempus facilisis ullamcorper. Nam sit amet suscipit risus, ut ultricies felis. Vivamus a finibus nisi. Sed quam sem, accumsan eget tristique sit amet, suscipit sit amet augue. Duis dolor dui, sagittis at faucibus ac, varius<\/p>\n","protected":false},"featured_media":249,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[22],"product_tag":[],"class_list":{"0":"post-248","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pet-essentials","7":"thunk-woo-product-list","8":"opn-qv-enable","9":"top-store-woo-hover-zoom","10":"top-store-single-product-tab-horizontal","11":"top-store-shadow-","12":"top-store-shadow-hover-","14":"first","15":"instock","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/wpthemes.themehunk.com\/pet-world\/wp-json\/wp\/v2\/product\/248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wpthemes.themehunk.com\/pet-world\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/wpthemes.themehunk.com\/pet-world\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/wpthemes.themehunk.com\/pet-world\/wp-json\/wp\/v2\/comments?post=248"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wpthemes.themehunk.com\/pet-world\/wp-json\/wp\/v2\/media\/249"}],"wp:attachment":[{"href":"https:\/\/wpthemes.themehunk.com\/pet-world\/wp-json\/wp\/v2\/media?parent=248"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/wpthemes.themehunk.com\/pet-world\/wp-json\/wp\/v2\/product_brand?post=248"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/wpthemes.themehunk.com\/pet-world\/wp-json\/wp\/v2\/product_cat?post=248"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/wpthemes.themehunk.com\/pet-world\/wp-json\/wp\/v2\/product_tag?post=248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}